{"id":134,"count":20,"description":"","link":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/","name":"Buletine informative","slug":"newsletter-ro","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buletine informative Archives - GagauziaDialogue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buletine informative Archives - GagauziaDialogue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/\" \/>\n<meta property=\"og:site_name\" content=\"GagauziaDialogue\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2020\/06\/gagauzia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/\",\"url\":\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/\",\"name\":\"Buletine informative Archives - GagauziaDialogue\",\"isPartOf\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/#breadcrumb\"},\"inLanguage\":\"ro-RO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gagauziadialogue.md\/ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buletine informative\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gagauziadialogue.md\/#website\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"name\":\"GagauziaDialogue\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gagauziadialogue.md\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\",\"name\":\"GagauziaDialogue\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"contentUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"width\":512,\"height\":512,\"caption\":\"GagauziaDialogue\"},\"image\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buletine informative Archives - GagauziaDialogue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/","og_locale":"ro_RO","og_type":"article","og_title":"Buletine informative Archives - GagauziaDialogue","og_url":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/","og_site_name":"GagauziaDialogue","og_image":[{"width":300,"height":240,"url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2020\/06\/gagauzia.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/","url":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/","name":"Buletine informative Archives - GagauziaDialogue","isPartOf":{"@id":"https:\/\/gagauziadialogue.md\/#website"},"breadcrumb":{"@id":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/#breadcrumb"},"inLanguage":"ro-RO"},{"@type":"BreadcrumbList","@id":"https:\/\/gagauziadialogue.md\/ro\/category\/newsletter-ro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gagauziadialogue.md\/ro\/"},{"@type":"ListItem","position":2,"name":"Buletine informative"}]},{"@type":"WebSite","@id":"https:\/\/gagauziadialogue.md\/#website","url":"https:\/\/gagauziadialogue.md\/","name":"GagauziaDialogue","description":"","publisher":{"@id":"https:\/\/gagauziadialogue.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gagauziadialogue.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/gagauziadialogue.md\/#organization","name":"GagauziaDialogue","url":"https:\/\/gagauziadialogue.md\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/","url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","contentUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","width":512,"height":512,"caption":"GagauziaDialogue"},"image":{"@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gagauziadialogue.md\/ro\/wp-json\/wp\/v2\/categories\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gagauziadialogue.md\/ro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gagauziadialogue.md\/ro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/gagauziadialogue.md\/ro\/wp-json\/wp\/v2\/posts?categories=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}