{"id":118,"count":6,"description":"","link":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/","name":"\u041e\u0442\u0447\u0435\u0442\u044b","slug":"reports-ru","taxonomy":"category","parent":115,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/\" \/>\n<meta property=\"og:site_name\" content=\"GagauziaDialogue\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2020\/06\/gagauzia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/\",\"url\":\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/\",\"name\":\"\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue\",\"isPartOf\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gagauziadialogue.md\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041e \u043f\u0440\u043e\u0435\u043a\u0442\u0435\",\"item\":\"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u041e\u0442\u0447\u0435\u0442\u044b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gagauziadialogue.md\/#website\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"name\":\"GagauziaDialogue\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gagauziadialogue.md\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\",\"name\":\"GagauziaDialogue\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"contentUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"width\":512,\"height\":512,\"caption\":\"GagauziaDialogue\"},\"image\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/","og_locale":"ru_RU","og_type":"article","og_title":"\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue","og_url":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/","og_site_name":"GagauziaDialogue","og_image":[{"width":300,"height":240,"url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2020\/06\/gagauzia.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/","url":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/","name":"\u041e\u0442\u0447\u0435\u0442\u044b Archives - GagauziaDialogue","isPartOf":{"@id":"https:\/\/gagauziadialogue.md\/#website"},"breadcrumb":{"@id":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/reports-ru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gagauziadialogue.md\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041e \u043f\u0440\u043e\u0435\u043a\u0442\u0435","item":"https:\/\/gagauziadialogue.md\/ru\/category\/about-the-project-ru\/"},{"@type":"ListItem","position":3,"name":"\u041e\u0442\u0447\u0435\u0442\u044b"}]},{"@type":"WebSite","@id":"https:\/\/gagauziadialogue.md\/#website","url":"https:\/\/gagauziadialogue.md\/","name":"GagauziaDialogue","description":"","publisher":{"@id":"https:\/\/gagauziadialogue.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gagauziadialogue.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/gagauziadialogue.md\/#organization","name":"GagauziaDialogue","url":"https:\/\/gagauziadialogue.md\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/","url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","contentUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","width":512,"height":512,"caption":"GagauziaDialogue"},"image":{"@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/categories\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/categories\/115"}],"wp:post_type":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/posts?categories=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}