{"id":33304,"date":"2024-11-27T14:53:15","date_gmt":"2024-11-27T12:53:15","guid":{"rendered":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/"},"modified":"2024-11-27T15:17:49","modified_gmt":"2024-11-27T13:17:49","slug":"costitutia-rm-si-legea-nr-344-in-rom-gag-rus","status":"publish","type":"post","link":"https:\/\/gagauziadialogue.md\/ru\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/","title":{"rendered":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/costitutia-TIPAR-1-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"\u0412\u0441\u0442\u0430\u0432\u043a\u0430 \u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f\/\u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u0410\u0422\u041e \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u044f\"><\/object><a id=\"wp-block-file--media-c3899fc9-67d4-4479-a093-158e635fbd0f\" href=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/costitutia-TIPAR-1-1.pdf\">\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f\/\u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u0410\u0422\u041e \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u044f<\/a><a href=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/costitutia-TIPAR-1-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-c3899fc9-67d4-4479-a093-158e635fbd0f\">Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":33300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[286,229,293],"tags":[],"class_list":["post-33304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category--ru","category-229","category-293"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\" \/>\n<meta property=\"og:site_name\" content=\"GagauziaDialogue\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T12:53:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T13:17:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1144\" \/>\n\t<meta property=\"og:image:height\" content=\"1408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lilia Loghinescu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lilia Loghinescu\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u043c\u0438\u043d\u0443\u0442\u0430\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\"},\"author\":{\"name\":\"Lilia Loghinescu\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/person\/30f480652891cf3eb391df59745e7812\"},\"headline\":\"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441\",\"datePublished\":\"2024-11-27T12:53:15+00:00\",\"dateModified\":\"2024-11-27T13:17:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\"},\"wordCount\":20,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\"},\"image\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png\",\"articleSection\":[\"\u0414\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b\",\"\u0414\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b\",\"\u041e\u0442\u0447\u0435\u0442\u044b \u0438 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b\"],\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\",\"url\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\",\"name\":\"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue\",\"isPartOf\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png\",\"datePublished\":\"2024-11-27T12:53:15+00:00\",\"dateModified\":\"2024-11-27T13:17:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage\",\"url\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png\",\"contentUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png\",\"width\":1144,\"height\":1408},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gagauziadialogue.md\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gagauziadialogue.md\/#website\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"name\":\"GagauziaDialogue\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gagauziadialogue.md\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/gagauziadialogue.md\/#organization\",\"name\":\"GagauziaDialogue\",\"url\":\"https:\/\/gagauziadialogue.md\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"contentUrl\":\"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png\",\"width\":512,\"height\":512,\"caption\":\"GagauziaDialogue\"},\"image\":{\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/person\/30f480652891cf3eb391df59745e7812\",\"name\":\"Lilia Loghinescu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/gagauziadialogue.md\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b1153a0b92eabbf984d4e9b0735bbfe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b1153a0b92eabbf984d4e9b0735bbfe?s=96&d=mm&r=g\",\"caption\":\"Lilia Loghinescu\"},\"url\":\"https:\/\/gagauziadialogue.md\/ru\/author\/lilia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/","og_locale":"ru_RU","og_type":"article","og_title":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue","og_url":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/","og_site_name":"GagauziaDialogue","article_published_time":"2024-11-27T12:53:15+00:00","article_modified_time":"2024-11-27T13:17:49+00:00","og_image":[{"width":1144,"height":1408,"url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png","type":"image\/png"}],"author":"Lilia Loghinescu","twitter_card":"summary_large_image","twitter_misc":{"\u041d\u0430\u043f\u0438\u0441\u0430\u043d\u043e \u0430\u0432\u0442\u043e\u0440\u043e\u043c":"Lilia Loghinescu","\u041f\u0440\u0438\u043c\u0435\u0440\u043d\u043e\u0435 \u0432\u0440\u0435\u043c\u044f \u0434\u043b\u044f \u0447\u0442\u0435\u043d\u0438\u044f":"1 \u043c\u0438\u043d\u0443\u0442\u0430"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#article","isPartOf":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/"},"author":{"name":"Lilia Loghinescu","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/person\/30f480652891cf3eb391df59745e7812"},"headline":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441","datePublished":"2024-11-27T12:53:15+00:00","dateModified":"2024-11-27T13:17:49+00:00","mainEntityOfPage":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/"},"wordCount":20,"commentCount":0,"publisher":{"@id":"https:\/\/gagauziadialogue.md\/#organization"},"image":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage"},"thumbnailUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png","articleSection":["\u0414\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b","\u0414\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b","\u041e\u0442\u0447\u0435\u0442\u044b \u0438 \u0434\u043e\u043a\u0443\u043c\u0435\u043d\u0442\u044b"],"inLanguage":"ru-RU","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/","url":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/","name":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441 - GagauziaDialogue","isPartOf":{"@id":"https:\/\/gagauziadialogue.md\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage"},"image":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage"},"thumbnailUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png","datePublished":"2024-11-27T12:53:15+00:00","dateModified":"2024-11-27T13:17:49+00:00","breadcrumb":{"@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#primaryimage","url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png","contentUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2024\/11\/Screenshot-2024-11-27-145233.png","width":1144,"height":1408},{"@type":"BreadcrumbList","@id":"https:\/\/gagauziadialogue.md\/costitutia-rm-si-legea-nr-344-in-rom-gag-rus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gagauziadialogue.md\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041a\u043e\u043d\u0441\u0442\u0438\u0442\u0443\u0446\u0438\u044f \u0420\u0435\u0441\u043f\u0443\u0431\u043b\u0438\u043a\u0438 \u041c\u043e\u043b\u0434\u043e\u0432\u0430 \u0438 \u0417\u0430\u043a\u043e\u043d \u043e\u0431 \u043e\u0441\u043e\u0431\u043e\u043c \u043f\u0440\u0430\u0432\u043e\u0432\u043e\u043c \u0441\u0442\u0430\u0442\u0443\u0441\u0435 \u0413\u0430\u0433\u0430\u0443\u0437\u0438\u0438 \u0432 \u0440\u0443\u043c\/\u0433\u0430\u0433\/\u0440\u0443\u0441"}]},{"@type":"WebSite","@id":"https:\/\/gagauziadialogue.md\/#website","url":"https:\/\/gagauziadialogue.md\/","name":"GagauziaDialogue","description":"","publisher":{"@id":"https:\/\/gagauziadialogue.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gagauziadialogue.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/gagauziadialogue.md\/#organization","name":"GagauziaDialogue","url":"https:\/\/gagauziadialogue.md\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/","url":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","contentUrl":"https:\/\/gagauziadialogue.md\/wp-content\/uploads\/2023\/06\/cropped-cropped-bulinuta-2-removebg-preview.png","width":512,"height":512,"caption":"GagauziaDialogue"},"image":{"@id":"https:\/\/gagauziadialogue.md\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/person\/30f480652891cf3eb391df59745e7812","name":"Lilia Loghinescu","image":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/gagauziadialogue.md\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2b1153a0b92eabbf984d4e9b0735bbfe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b1153a0b92eabbf984d4e9b0735bbfe?s=96&d=mm&r=g","caption":"Lilia Loghinescu"},"url":"https:\/\/gagauziadialogue.md\/ru\/author\/lilia\/"}]}},"_links":{"self":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/posts\/33304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/comments?post=33304"}],"version-history":[{"count":3,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/posts\/33304\/revisions"}],"predecessor-version":[{"id":33315,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/posts\/33304\/revisions\/33315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/media\/33300"}],"wp:attachment":[{"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/media?parent=33304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/categories?post=33304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gagauziadialogue.md\/ru\/wp-json\/wp\/v2\/tags?post=33304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}